{"id":80874,"count":1,"description":"","link":"https:\/\/bewaf.com\/blog\/tag\/%e3%83%80%e3%82%a4%e3%83%af-19-%e3%82%a2%e3%83%ab%e3%83%95%e3%82%a1%e3%82%b9-ct-sv-70l-00614118-%e3%81%ae%e3%83%91%e3%83%bc%e3%83%84%e3%83%aa%e3%82%b9%e3%83%88%e3%81%af%e3%82%b3%e3%83%81%e3%83%a9\/","name":"\u30bf\u3099\u30a4\u30ef 19 \u30a2\u30eb\u30d5\u30a1\u30b9 CT SV 70L (00614118) \u306e\u30d1\u30fc\u30c4\u30ea\u30b9\u30c8\u306f\u30b3\u30c1\u30e9!!","slug":"%e3%83%80%e3%82%a4%e3%83%af-19-%e3%82%a2%e3%83%ab%e3%83%95%e3%82%a1%e3%82%b9-ct-sv-70l-00614118-%e3%81%ae%e3%83%91%e3%83%bc%e3%83%84%e3%83%aa%e3%82%b9%e3%83%88%e3%81%af%e3%82%b3%e3%83%81%e3%83%a9","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bewaf.com\/blog\/wp-json\/wp\/v2\/tags\/80874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bewaf.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bewaf.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bewaf.com\/blog\/wp-json\/wp\/v2\/posts?tags=80874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}